{"id":132,"date":"2020-03-25T00:00:00","date_gmt":"2020-03-25T06:00:00","guid":{"rendered":"https:\/\/fematur.net\/?p=132"},"modified":"2023-10-09T22:39:09","modified_gmt":"2023-10-10T03:39:09","slug":"fematur-da-seguimiento-a-acciones-del-wttc","status":"publish","type":"post","link":"https:\/\/fematur.net\/index.php\/2020\/03\/25\/fematur-da-seguimiento-a-acciones-del-wttc\/","title":{"rendered":"FEMATUR da seguimiento a acciones del WTTC"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"740\" height=\"309\" src=\"https:\/\/fematur.net\/wp-content\/uploads\/2023\/10\/904172_e179a0279dcd498a8a7c2929fcf4637emv2.webp\" alt=\"\" class=\"wp-image-128\" srcset=\"https:\/\/fematur.net\/wp-content\/uploads\/2023\/10\/904172_e179a0279dcd498a8a7c2929fcf4637emv2.webp 740w, https:\/\/fematur.net\/wp-content\/uploads\/2023\/10\/904172_e179a0279dcd498a8a7c2929fcf4637emv2-300x125.webp 300w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<p id=\"viewer-89e4k\">A toda la comunidad tur\u00edstica mexicana.<\/p>\n\n\n\n<p id=\"viewer-a9r77\">A la opini\u00f3n p\u00fablica.<\/p>\n\n\n\n<p id=\"viewer-935p0\">La Federaci\u00f3n Mexicana de Asociaciones Tur\u00edsticas (FEMATUR) comparte la Carta Abierta, que emiti\u00f3 el d\u00eda de hoy, el Consejo Mundial de Viajes y Turismo (WTTC), con cifras al 25 de marzo, sobre la evoluci\u00f3n y el impacto, que el coronavirus est\u00e1 provocando en el mundo entero y en particular en el turismo.<\/p>\n\n\n\n<p id=\"viewer-5f45e\">Por cuestiones de oportunidad en la informaci\u00f3n, el documento est\u00e1 disponible solamente en el idioma ingl\u00e9s, que es de uso generalizado en la industria de los viajes.<\/p>\n\n\n\n<p id=\"viewer-1dhjf\">Adem\u00e1s, incluimos el reciente comunicado que emiti\u00f3 el WTTC, donde estima que la p\u00e9rdida de empleos en el sector de viajes ser\u00e1 de 75 millones, y no de 50 millones como lo dijo anteriormente.<\/p>\n\n\n\n<p id=\"viewer-73kfj\">Reiteramos las tres consideraciones m\u00e1s importantes, que hace este importante organismo internacional.<\/p>\n\n\n\n<p id=\"viewer-7t1to\">1. La superaci\u00f3n de esta crisis in\u00e9dita, requiere de ayuda financiera para proteger los ingresos de millones de trabajadores en el sector turismo, que enfrentan severas dificultades econ\u00f3micas.<\/p>\n\n\n\n<p id=\"viewer-dtla9\">2. Los gobiernos deben otorgar pr\u00e9stamos sin intereses a las empresas tur\u00edsticas y a millones de peque\u00f1as y medianas empresas, como un est\u00edmulo para impedir su colapso.<\/p>\n\n\n\n<p id=\"viewer-cdkdo\">3. Todos los impuestos, derechos y obligaciones financieras deben ser diferidas inmediatamente al menos durante los pr\u00f3ximos 12 meses.<\/p>\n\n\n\n<p id=\"viewer-8e2m1\">FEMATUR seguir\u00e1 participando cotidianamente en el seguimiento de las acciones del Consejo Mundial de Viajes y Turismo, que es el organismo empresarial tur\u00edstico m\u00e1s importante del mundo y al que FEMATUR est\u00e1 adherido.<\/p>\n\n\n\n<p id=\"viewer-f4krb\">Atentamente<\/p>\n\n\n\n<p id=\"viewer-90je1\">Dr. Jorge Hern\u00e1ndez Delgado<\/p>\n\n\n\n<p id=\"viewer-dpjt1\">Presidente de FEMATUR<\/p>\n\n\n\n<p id=\"viewer-63b32\">Consulta los documentos del WTTC en los siguientes enlaces:<\/p>\n\n\n\n<p id=\"viewer-bmgvh\"><a href=\"https:\/\/90417270-9353-47a1-8bd5-0929bb4fa4fe.usrfiles.com\/ugd\/904172_fc65d0416ad345a180f414ab826fd8e2.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><u>WTTC CORONAVIRUS BRIEF<\/u><\/a><\/p>\n\n\n\n<p id=\"viewer-f1k20\"><a href=\"https:\/\/90417270-9353-47a1-8bd5-0929bb4fa4fe.usrfiles.com\/ugd\/904172_bfe4f3b7a9f749928b8ff2bea5703847.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><u>COVID-19. OPEN LETTER FROM THE WTTC<\/u><\/a><\/p>\n\n\n\n<p id=\"viewer-68s62\"><a href=\"https:\/\/90417270-9353-47a1-8bd5-0929bb4fa4fe.usrfiles.com\/ugd\/904172_213c47747d10433290d88213c67c70da.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><u>AUMENTA WTTC CIFRA ESTIMADA DE P\u00c9RDIDA DE EMPLEOS POR COVID-19<\/u><\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Federaci\u00f3n Mexicana de Asociaciones Tur\u00edsticas (FEMATUR) comparte la Carta Abierta, que emiti\u00f3 el d\u00eda de hoy, el Consejo Mundial de Viajes y Turismo (WTTC), con cifras al 25 de marzo, sobre la evoluci\u00f3n y el impacto, que el coronavirus est\u00e1 provocando en el mundo entero y en particular en el turismo.<\/p>\n","protected":false},"author":1,"featured_media":128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"acf":{"es_video":false,"es_evento":false,"es_consejo":false},"thumbnail":"https:\/\/fematur.net\/wp-content\/uploads\/2023\/10\/904172_e179a0279dcd498a8a7c2929fcf4637emv2.webp","_links":{"self":[{"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/posts\/132"}],"collection":[{"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/comments?post=132"}],"version-history":[{"count":1,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/posts\/132\/revisions"}],"predecessor-version":[{"id":133,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/posts\/132\/revisions\/133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/media\/128"}],"wp:attachment":[{"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/media?parent=132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/categories?post=132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/tags?post=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}