{"id":281,"date":"2020-10-02T16:36:00","date_gmt":"2020-10-02T21:36:00","guid":{"rendered":"https:\/\/fematur.net\/?p=281"},"modified":"2025-07-10T16:38:19","modified_gmt":"2025-07-10T22:38:19","slug":"el-turismo-y-el-financiamiento","status":"publish","type":"post","link":"https:\/\/fematur.net\/index.php\/2020\/10\/02\/el-turismo-y-el-financiamiento\/","title":{"rendered":"EL TURISMO Y EL FINANCIAMIENTO"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"740\" height=\"493\" src=\"https:\/\/fematur.net\/wp-content\/uploads\/2025\/07\/money.jpg\" alt=\"\" class=\"wp-image-282\" srcset=\"https:\/\/fematur.net\/wp-content\/uploads\/2025\/07\/money.jpg 740w, https:\/\/fematur.net\/wp-content\/uploads\/2025\/07\/money-300x200.jpg 300w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<p id=\"viewer-ane2t\">Uno de los aspectos que m\u00e1s envidia y hasta resentimiento ha generado entre los prestadores de servicios tur\u00edsticos mexicanos, en la estrategia de recuperaci\u00f3n por el covid 19, ha sido la percepci\u00f3n que el resto de los gobiernos del mundo, han desplegado varias opciones de apoyo financiero a sus empresarios, que aparentemente en el caso mexicano, brillan por su ausencia.<\/p>\n\n\n\n<p id=\"viewer-c8t2i\">La inadecuada cultura financiera, es uno de los principales problemas que enfrentan nuestros emprendedores y empresarios, lo que no es diferente en casi cualquier otro sector de la econom\u00eda, pero es en momentos de emergencia econ\u00f3mica, como el que sin duda atravesamos en este momento, cuando el capital financiero, se presenta como el principal freno u obst\u00e1culo, para sacar a flote cualquier negocio en marcha.<\/p>\n\n\n\n<p id=\"viewer-301ct\">En este webinar, el Lic. Gerardo Corona Gonz\u00e1lez, nos expondr\u00e1 su visi\u00f3n, del papel que juega el elemento financiero en la operaci\u00f3n de los principales negocios tur\u00edsticos; desde una aerol\u00ednea como Aerom\u00e9xico, Interjet o Volaris, hasta un campamento ecotur\u00edstico en una zona ind\u00edgena, pasando por los autotransportistas, los hoteleros, tanto de cadena como los independientes, los restauranteros, los agentes de viajes y los desarrolladores de tecnolog\u00eda, que a veces requieren un apoyo relativamente modesto para alg\u00fan desarrollo o aplicaci\u00f3n innovadora.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"740\" height=\"380\" src=\"https:\/\/fematur.net\/wp-content\/uploads\/2025\/07\/playa4.jpg\" alt=\"\" class=\"wp-image-283\" srcset=\"https:\/\/fematur.net\/wp-content\/uploads\/2025\/07\/playa4.jpg 740w, https:\/\/fematur.net\/wp-content\/uploads\/2025\/07\/playa4-300x154.jpg 300w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<p id=\"viewer-ejt4j\">La aparentemente compleja red de instituciones financieras, ya sean de alcance internacional, como el Banco Mundial o el BID, la banca de desarrollo, como Banobras, Bancomext o Nacional Financiera; la banca comercial privada y otros apoyos como las cajas de ahorro o las sociedades de financiamiento diverso, se presentan como un ecuaci\u00f3n indescifrable para el empresario tur\u00edstico, generalmente mejor dotado en cualidades de anfitrion\u00eda y creatividad, que en cultura financiera.<\/p>\n\n\n\n<p id=\"viewer-70d0s\">Hemos venido escuchando pron\u00f3sticos sombr\u00edos, de la reducci\u00f3n del Producto Interno Bruto, de la necesidad de contratar mayor Deuda P\u00fablica o no, de promover un presupuesto p\u00fablico moderado o desbordado, de expandir o reducir nuestros negocios, de contratar cr\u00e9ditos o sanear nuestras finanzas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"740\" height=\"487\" src=\"https:\/\/fematur.net\/wp-content\/uploads\/2025\/07\/cel.jpg\" alt=\"\" class=\"wp-image-284\" srcset=\"https:\/\/fematur.net\/wp-content\/uploads\/2025\/07\/cel.jpg 740w, https:\/\/fematur.net\/wp-content\/uploads\/2025\/07\/cel-300x197.jpg 300w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<p id=\"viewer-5m7lg\">La gran experiencia del Lic. Gerardo Corona Gonz\u00e1lez, quien como funcionario p\u00fablico financiero, intervino en la mayor\u00eda de los proyectos importantes que componen la actual infraestructura tur\u00edstica mexicana, complementada por su visi\u00f3n como Subsecretario de Turismo, durante la gesti\u00f3n del Mtro. Enrique de la Madrid Cordero, (2016-2018) y su actual desempe\u00f1o como consultor y asesor de empresas de gran calado tur\u00edstico; aunado a su gran capacidad did\u00e1ctica y de formador de j\u00f3venes emprendedores, abordar\u00e1 todos estos temas y nos permitir\u00e1 sin duda, actualizarnos y calibrar con mayor precisi\u00f3n, el camino financiero m\u00e1s factible y recomendable en esta \u00e9poca de transformaci\u00f3n y reinvenci\u00f3n para todos los que nos dedicamos al turismo.<\/p>\n\n\n\n<p id=\"viewer-a8nvp\">Acomp\u00e1\u00f1anos el pr\u00f3ximo mi\u00e9rcoles 7 de octubre a las 18:00 horas v\u00eda zoom (<a target=\"_blank\" href=\"https:\/\/zoom.us\/j\/93325911831\" rel=\"noreferrer noopener\"><u>https:\/\/zoom.us\/j\/93325911831<\/u><\/a>) para abordar este importante tema.<\/p>\n\n\n\n<p id=\"viewer-29olq\">No te lo pierdas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los aspectos que m\u00e1s envidia y hasta resentimiento ha generado entre los prestadores de servicios tur\u00edsticos mexicanos<\/p>\n","protected":false},"author":1,"featured_media":282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"acf":{"es_video":false,"es_evento":false,"es_consejo":false},"thumbnail":"https:\/\/fematur.net\/wp-content\/uploads\/2025\/07\/money.jpg","_links":{"self":[{"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/posts\/281"}],"collection":[{"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":1,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/posts\/281\/revisions"}],"predecessor-version":[{"id":285,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/posts\/281\/revisions\/285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/media?parent=281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/categories?post=281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fematur.net\/index.php\/wp-json\/wp\/v2\/tags?post=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}